{"id":5517,"date":"2015-12-28T16:15:05","date_gmt":"2015-12-28T16:15:05","guid":{"rendered":"https:\/\/agefriendlyworld.local.org\/?p=5517"},"modified":"2016-01-05T12:42:48","modified_gmt":"2016-01-05T12:42:48","slug":"convivio-de-natal-reune-mais-de-500-idosos","status":"publish","type":"post","link":"https:\/\/extranet.who.int\/agefriendlyworld\/convivio-de-natal-reune-mais-de-500-idosos\/","title":{"rendered":"Conv\u00edvio de Natal re\u00fane mais de 500 idosos"},"content":{"rendered":"<p>No desenvolvimento de um conjunto de pol\u00edticas sociais de apoio e acompanhamento dos idosos no concelho e no \u00e2mbito das comemora\u00e7\u00f5es de Natal do munic\u00edpio de Castro Marim, a autarquia organizou o\u00adntem um conv\u00edvio destinado aos seniores do concelho. Mais de 500 idosos passaram um dia diferente, num almo\u00e7o-conv\u00edvio seguido de muita anima\u00e7\u00e3o.<\/p>\n<p>Com a atua\u00e7\u00e3o especial de Ant\u00f3nio Calv\u00e1rio, um dos \u00edcones da m\u00fasica portuguesa, a anima\u00e7\u00e3o continuou com o grupo de baile \u201c+2\u201d.<\/p>\n<p>Com esta iniciativa, a autarquia quis propiciar aos idosos de Castro Marim, que muito t\u00eam contribu\u00eddo para a constru\u00e7\u00e3o de um concelho mais evolu\u00eddo e solid\u00e1rio, uma tarde de homenagem, de conv\u00edvio e de partilha dos valores da amizade e da fraternidade de uma faixa muito significativa da popula\u00e7\u00e3o castromarinense.<\/p>\n<p>\u201cTudo faremos para que possam envelhecer com dignidade, com mais qualidade de vida, para que possam dar vida aos anos\u201d, assegurou o presidente da C\u00e2mara Municipal, Francisco Amaral<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No desenvolvimento de um conjunto de pol\u00edticas sociais de apoio e acompanhamento dos idosos no concelho e no \u00e2mbito das comemora\u00e7\u00f5es de Natal do munic\u00edpio de Castro Marim, a autarquia organizou o\u00adntem um conv\u00edvio destinado aos seniores do concelho. Mais de 500 idosos passaram um dia diferente, num almo\u00e7o-conv\u00edvio seguido de muita anima\u00e7\u00e3o.<\/p>\n<p>Com a atua\u00e7\u00e3o especial de Ant\u00f3nio Calv\u00e1rio, um dos \u00edcones da m\u00fasica portuguesa, a anima\u00e7\u00e3o continuou com o grupo de baile \u201c+2\u201d.<\/p>\n<p>Com esta iniciativa, a autarquia quis propiciar aos idosos de Castro Marim, que muito t\u00eam contribu\u00eddo para a constru\u00e7\u00e3o de um concelho mais evolu\u00eddo e solid\u00e1rio, uma tarde de homenagem, de conv\u00edvio e de partilha dos valores da amizade e da fraternidade de uma faixa muito significativa da popula\u00e7\u00e3o castromarinense.<\/p>\n<p>\u201cTudo faremos para que possam envelhecer com dignidade, com mais qualidade de vida, para que possam dar vida aos anos\u201d, assegurou o presidente da C\u00e2mara Municipal, Francisco Amaral<\/p>\n","protected":false},"author":125,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"categories":[550],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/extranet.who.int\/agefriendlyworld\/wp-json\/wp\/v2\/posts\/5517"}],"collection":[{"href":"https:\/\/extranet.who.int\/agefriendlyworld\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/extranet.who.int\/agefriendlyworld\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/extranet.who.int\/agefriendlyworld\/wp-json\/wp\/v2\/users\/125"}],"replies":[{"embeddable":true,"href":"https:\/\/extranet.who.int\/agefriendlyworld\/wp-json\/wp\/v2\/comments?post=5517"}],"version-history":[{"count":2,"href":"https:\/\/extranet.who.int\/agefriendlyworld\/wp-json\/wp\/v2\/posts\/5517\/revisions"}],"predecessor-version":[{"id":5519,"href":"https:\/\/extranet.who.int\/agefriendlyworld\/wp-json\/wp\/v2\/posts\/5517\/revisions\/5519"}],"wp:attachment":[{"href":"https:\/\/extranet.who.int\/agefriendlyworld\/wp-json\/wp\/v2\/media?parent=5517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/extranet.who.int\/agefriendlyworld\/wp-json\/wp\/v2\/categories?post=5517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/extranet.who.int\/agefriendlyworld\/wp-json\/wp\/v2\/tags?post=5517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}